{"id":349,"date":"2024-03-23T08:31:56","date_gmt":"2024-03-23T12:31:56","guid":{"rendered":"https:\/\/betcaliforniasports.com\/?page_id=349"},"modified":"2024-03-27T12:42:17","modified_gmt":"2024-03-27T16:42:17","slug":"contests","status":"publish","type":"page","link":"https:\/\/betcaliforniasports.com\/index.php\/contests\/","title":{"rendered":"Contests"},"content":{"rendered":"\n<div id=\"get_caas_lobby\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/betcaliforniasports.com\/index.php\/wp-json\/wp\/v2\/pages\/349"}],"collection":[{"href":"https:\/\/betcaliforniasports.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/betcaliforniasports.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/betcaliforniasports.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/betcaliforniasports.com\/index.php\/wp-json\/wp\/v2\/comments?post=349"}],"version-history":[{"count":8,"href":"https:\/\/betcaliforniasports.com\/index.php\/wp-json\/wp\/v2\/pages\/349\/revisions"}],"predecessor-version":[{"id":474,"href":"https:\/\/betcaliforniasports.com\/index.php\/wp-json\/wp\/v2\/pages\/349\/revisions\/474"}],"wp:attachment":[{"href":"https:\/\/betcaliforniasports.com\/index.php\/wp-json\/wp\/v2\/media?parent=349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}